{"id":587,"date":"2024-11-27T15:34:25","date_gmt":"2024-11-27T15:34:25","guid":{"rendered":"https:\/\/femaluma.com\/?page_id=587"},"modified":"2026-06-10T15:24:13","modified_gmt":"2026-06-10T15:24:13","slug":"artist","status":"publish","type":"page","link":"https:\/\/femaluma.com\/pt\/artist\/","title":{"rendered":"Artistas"},"content":{"rendered":"<div id=\"fws_6a57375a6a64e\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"impact\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"7%\" data-bottom-percent=\"6%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  top_margin_-5pct right_padding_8pct left_padding_8pct top_padding_tablet_20pct bottom_padding_tablet_15pct top_margin_tablet_0px\"  style=\"padding-top: calc(100vw * 0.07); padding-bottom: calc(100vw * 0.06); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57375a6abb8\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  bottom_padding_tablet_6pct\"  style=\"padding-bottom: 3%; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_size_3vw font_line_height_1-5\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"none\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 3vw; line-height: 3.3vw;\"><h3 >Represented artists<\/h3><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"nectar-flickity not-initialized nectar-carousel tb-spacing-0 vertical-alignment-bottom\" data-centered-cells=\"true\" data-pause-on-hover=\"\" data-touch-icon-color=\"default\" data-control-color=\"accent-color\" data-overflow=\"visible\" data-r-bottom-total=\"\" data-drag-scale=\"\" data-wrap=\"no-wrap\" data-spacing=\"10px\" data-controls=\"next_prev_arrows_overlaid\" data-pagination-alignment=\"default\" data-adaptive-height=\"\" data-border-radius=\"none\" data-column-border=\"\" data-column-padding=\"0\" data-format=\"default\" data-autoplay=\"\" data-autoplay-dur=\"5000\" data-control-style=\"material_pagination\" data-desktop-columns=\"3\" data-small-desktop-columns=\"2\" data-tablet-columns=\"2\" data-phone-columns=\"1\" data-column-color=\"\"><div class=\"flickity-viewport\"> <div class=\"flickity-slider\"><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"nectar-fancy-box using-img  min_height_tablet_550px hover_o_opacity_0-4 o_opacity_0-9 hover_color_0a0202 icon_position_top disable-hover-movement\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"none\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"parallax-layer\"><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/femaluma.com\/wp-content\/uploads\/2024\/08\/JT-pb.jpg\"><\/div><\/div><div class=\"inner\"><div class=\"heading-wrap\">\n<h4>Joana Tubal<\/h4>\n<\/div><div class=\"hover-content\">Ver mais<\/div><\/div>  <a  href=\"\/pt\/artist\/joana-tubal\/\" class=\"box-link\"><\/a> <\/div><\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"nectar-fancy-box using-img  min_height_tablet_550px hover_o_opacity_0-4 o_opacity_0-9 hover_color_000000 icon_position_top disable-hover-movement\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"none\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"parallax-layer\"><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/femaluma.com\/wp-content\/uploads\/2026\/04\/marcelolamarca-2.jpg\"><\/div><\/div><div class=\"inner\"><div class=\"heading-wrap\">\n<h4>Marcelo Lamarca<\/h4>\n<\/div><div class=\"hover-content\">Ver mais<\/div><\/div>  <a  href=\"\/pt\/artist\/marcelo-lamarca\/\" class=\"box-link\"><\/a> <\/div><\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"nectar-fancy-box using-img  min_height_tablet_550px hover_o_opacity_0-4 o_opacity_0-9 hover_color_000000 icon_position_top disable-hover-movement\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"none\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"parallax-layer\"><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/femaluma.com\/wp-content\/uploads\/2026\/03\/suzana-pb-2.jpg\"><\/div><\/div><div class=\"inner\"><div class=\"heading-wrap\">\n<h4>Suzana Queiroga<\/h4>\n<\/div><div class=\"hover-content\">Ver mais<\/div><\/div>  <a  href=\"\/pt\/artist\/suzana-queiroga\/\" class=\"box-link\"><\/a> <\/div><\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"nectar-fancy-box using-img  min_height_tablet_550px hover_o_opacity_0-4 o_opacity_0-9 hover_color_000000 icon_position_top disable-hover-movement\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"none\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"parallax-layer\"><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/femaluma.com\/wp-content\/uploads\/2026\/04\/rebeca.jpg\"><\/div><\/div><div class=\"inner\"><div class=\"heading-wrap\">\n<h4>Rebeca Sellitti<\/h4>\n<\/div><div class=\"hover-content\">Ver mais<\/div><\/div>  <a  href=\"\/pt\/artist\/rebeca-sellitt\/\" class=\"box-link\"><\/a> <\/div><\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"nectar-fancy-box using-img  min_height_tablet_550px hover_o_opacity_0-4 o_opacity_0-9 hover_color_000000 icon_position_top disable-hover-movement\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"none\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"parallax-layer\"><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/femaluma.com\/wp-content\/uploads\/2026\/04\/seon.jpg\"><\/div><\/div><div class=\"inner\"><div class=\"heading-wrap\">\n<h4>Seon Ghi Bahk<\/h4>\n<\/div><div class=\"hover-content\">Ver mais<\/div><\/div>  <a  href=\"\/pt\/artist\/seon\/\" class=\"box-link\"><\/a> <\/div><\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"nectar-fancy-box using-img  min_height_tablet_550px hover_o_opacity_0-4 o_opacity_0-9 hover_color_000000 icon_position_top disable-hover-movement\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"none\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"parallax-layer\"><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/femaluma.com\/wp-content\/uploads\/2026\/06\/frida.jpg\"><\/div><\/div><div class=\"inner\"><div class=\"heading-wrap\">\n<h4>Frida Baranek<\/h4>\n<\/div><div class=\"hover-content\">Ver mais<\/div><\/div>  <a  href=\"\/pt\/artist\/frida-baranek\/\" class=\"box-link\"><\/a> <\/div><\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"nectar-fancy-box using-img  min_height_tablet_550px hover_o_opacity_0-4 o_opacity_0-9 hover_color_000000 icon_position_top disable-hover-movement\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"none\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"parallax-layer\"><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/femaluma.com\/wp-content\/uploads\/2026\/06\/famakan.jpg\"><\/div><\/div><div class=\"inner\"><div class=\"heading-wrap\">\n<h4>Famakan Magassa<\/h4>\n<\/div><div class=\"hover-content\">Ver mais<\/div><\/div>  <a  href=\"\/pt\/artist\/famakan-magassa\/\" class=\"box-link\"><\/a> <\/div><\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"nectar-fancy-box using-img  min_height_tablet_550px hover_o_opacity_0-4 o_opacity_0-9 hover_color_000000 icon_position_top disable-hover-movement\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" style=\"min-height: 70vh\" data-style=\"hover_desc\" data-border-radius=\"default\" data-animation=\"\" data-bg-animation=\"none\" data-border=\"\" data-delay=\"\" data-alignment=\"left\" data-color=\"accent-color\" ><div class=\"parallax-layer\"><div class=\"box-bg\"  data-nectar-img-src=\"https:\/\/femaluma.com\/wp-content\/uploads\/2026\/06\/ana-coutinho-.jpg\"><\/div><\/div><div class=\"inner\"><div class=\"heading-wrap\">\n<h4>Ana Coutinho<\/h4>\n<\/div><div class=\"hover-content\">Ver mais<\/div><\/div>  <a  href=\"\/pt\/artist\/ana-coutinho\/\" class=\"box-link\"><\/a> <\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Represented artists Joana Tubal View more Marcelo Lamarca View more Suzana Queiroga View more Rebeca Sellitti View more...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-587","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/femaluma.com\/pt\/wp-json\/wp\/v2\/pages\/587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/femaluma.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/femaluma.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/femaluma.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/femaluma.com\/pt\/wp-json\/wp\/v2\/comments?post=587"}],"version-history":[{"count":21,"href":"https:\/\/femaluma.com\/pt\/wp-json\/wp\/v2\/pages\/587\/revisions"}],"predecessor-version":[{"id":893,"href":"https:\/\/femaluma.com\/pt\/wp-json\/wp\/v2\/pages\/587\/revisions\/893"}],"wp:attachment":[{"href":"https:\/\/femaluma.com\/pt\/wp-json\/wp\/v2\/media?parent=587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}